{"id":87,"count":1,"description":"","link":"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/","name":"agroindustria mexicana","slug":"agroindustria-mexicana","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>agroindustria mexicana archivos - Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"agroindustria mexicana archivos - Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/\" \/>\n<meta property=\"og:site_name\" content=\"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mexfrut.com\/blog\/wp-content\/uploads\/2025\/11\/Diseno-sin-titulo-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/tag\\\/agroindustria-mexicana\\\/\",\"url\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/tag\\\/agroindustria-mexicana\\\/\",\"name\":\"agroindustria mexicana archivos - Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/tag\\\/agroindustria-mexicana\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/tag\\\/agroindustria-mexicana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"agroindustria mexicana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/\",\"name\":\"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas\",\"description\":\"Contenido especializado sobre aguacate, lim\u00f3n persa, mango y frutos rojos: consejos, datos \u00fatiles, recetas, tendencias del sector y todo lo relacionado con la industria frut\u00edcola.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/#organization\",\"name\":\"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas\",\"url\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Logo-Mexfrut.fw_.png\",\"contentUrl\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Logo-Mexfrut.fw_.png\",\"width\":1065,\"height\":520,\"caption\":\"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas\"},\"image\":{\"@id\":\"https:\\\/\\\/mexfrut.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mexfrut\",\"https:\\\/\\\/www.instagram.com\\\/mexfrutsrl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"agroindustria mexicana archivos - Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/","og_locale":"es_MX","og_type":"article","og_title":"agroindustria mexicana archivos - Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas","og_url":"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/","og_site_name":"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas","og_image":[{"width":1200,"height":675,"url":"https:\/\/mexfrut.com\/blog\/wp-content\/uploads\/2025\/11\/Diseno-sin-titulo-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/","url":"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/","name":"agroindustria mexicana archivos - Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas","isPartOf":{"@id":"https:\/\/mexfrut.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/mexfrut.com\/blog\/tag\/agroindustria-mexicana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/mexfrut.com\/blog\/"},{"@type":"ListItem","position":2,"name":"agroindustria mexicana"}]},{"@type":"WebSite","@id":"https:\/\/mexfrut.com\/blog\/#website","url":"https:\/\/mexfrut.com\/blog\/","name":"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas","description":"Contenido especializado sobre aguacate, lim\u00f3n persa, mango y frutos rojos: consejos, datos \u00fatiles, recetas, tendencias del sector y todo lo relacionado con la industria frut\u00edcola.","publisher":{"@id":"https:\/\/mexfrut.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mexfrut.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mexfrut.com\/blog\/#organization","name":"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas","url":"https:\/\/mexfrut.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mexfrut.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/mexfrut.com\/blog\/wp-content\/uploads\/2025\/11\/Logo-Mexfrut.fw_.png","contentUrl":"https:\/\/mexfrut.com\/blog\/wp-content\/uploads\/2025\/11\/Logo-Mexfrut.fw_.png","width":1065,"height":520,"caption":"Mexfrut | Producci\u00f3n, exportaci\u00f3n y mercado del aguacate Hass mexicano y frutas finas"},"image":{"@id":"https:\/\/mexfrut.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mexfrut","https:\/\/www.instagram.com\/mexfrutsrl\/"]}]}},"_links":{"self":[{"href":"https:\/\/mexfrut.com\/blog\/wp-json\/wp\/v2\/tags\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexfrut.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mexfrut.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mexfrut.com\/blog\/wp-json\/wp\/v2\/posts?tags=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}